{"id":5108,"date":"2025-02-07T21:06:26","date_gmt":"2025-02-07T21:06:26","guid":{"rendered":"https:\/\/banzai.pt\/pixel-2\/"},"modified":"2026-04-14T16:19:16","modified_gmt":"2026-04-14T16:19:16","slug":"pixel-2","status":"publish","type":"page","link":"https:\/\/banzai.pt\/es\/pixel-2\/","title":{"rendered":"P\u00edxel"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb video_bg=\u00bbuse_video\u00bb video_webm=\u00bbhttps:\/\/banzai.pt\/wp-content\/uploads\/2025\/02\/banzai-pixel-teaser1-480p-nosound.webm\u00bb background_video_loading=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb advanced_gradient=\u00bblinear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,252) 0%, rgba(0,0,0,0) 43%)\u00bb enable_shape_divider=\u00bbtrue\u00bb shape_divider_position=\u00bbboth\u00bb bg_image_animation=\u00bbzoom-out\u00bb mobile_disable_bg_image_animation=\u00bbtrue\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbmedium_fast\u00bb gradient_type=\u00bbadvanced\u00bb shape_type=\u00bbcurve\u00bb advanced_gradient_display_type=\u00bblinear\u00bb][vc_column bottom_padding_desktop=\u00bb40px\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_margin=\u00bb10px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner right_padding_desktop=\u00bb15%\u00bb right_padding_tablet=\u00bb50%\u00bb right_padding_phone=\u00bb15%\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][split_line_heading line_reveal_by_space_text_effect=\u00bbletter-reveal-bottom\u00bb font_style=\u00bbh1&#8243; stagger_animation=\u00bbtrue\u00bb font_size_max=\u00bb108px\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb animation_type=\u00bbline-reveal-by-space\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbP\u00edxel\u00bb text_direction=\u00bbdefault\u00bb font_size=\u00bb6vw\u00bb font_line_height=\u00bb1&#8243; font_size_tablet=\u00bb10vw\u00bb font_size_phone=\u00bb12vw\u00bb][\/split_line_heading][\/vc_column_inner][vc_column_inner left_padding_desktop=\u00bb30%\u00bb left_padding_tablet=\u00bb0&#8243; right_padding_tablet=\u00bb30%\u00bb right_padding_phone=\u00bb0&#8243; flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb delay=\u00bb300&#8243; offset=\u00bbvc_col-xs-9&#8243;][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_min=\u00bb16px\u00bb font_size_max=\u00bb22px\u00bb font_size_desktop=\u00bb1.3vw\u00bb font_line_height=\u00bb1.6&#8243; text_direction=\u00bbdefault\u00bb max_width=\u00bb375px\u00bb]\u00a1Piensa, mu\u00e9vete, salta! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando![\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbright\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb delay=\u00bb500&#8243; offset=\u00bbvc_col-xs-3&#8243;][nectar_cta btn_style=\u00bbnext-section\u00bb btn_type=\u00bbminimal-arrow\u00bb alignment=\u00bbright\u00bb alignment_tablet=\u00bbright\u00bb alignment_phone=\u00bbdefault\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#AE56E5&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb top_padding_tablet=\u00bb16%\u00bb bottom_padding_tablet=\u00bb16%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb enable_shape_divider=\u00bbtrue\u00bb shape_divider_position=\u00bbboth\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bbcurve\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bb0px\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_margin=\u00bbnone\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb30&#8243; bottom_padding_tablet=\u00bb20&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-5-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bb5px\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#FFFFFF\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbsmall_desktop\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb content_layout=\u00bbdefault\u00bb][image_with_animation image_url=\u00bb5643&#8243; image_size=\u00bbmedium\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb animation_type=\u00bbentrance\u00bb animation=\u00bbNone\u00bb animation_movement_type=\u00bbtransform_y\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bb\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h2>\u00a1Una aventura \u00e9pica en la que cada paso cuenta para la victoria!<\/h2>\n[\/vc_column_text][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1Descubre una m\u00e1gica arena de p\u00edxeles donde el suelo cobra vida a cada paso! \u00bfHas jugado alguna vez a \u00abThe Floor is Lava\u00bb? <\/p>\n<p>Salta, corre y supera incre\u00edbles desaf\u00edos en solitario o en equipo. \u00a1Parpadea con los LED correctos y gana puntuaciones \u00e9picas en un juego lleno de adrenalina y diversi\u00f3n![\/vc_column_text][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][nectar_cta btn_style=\u00bbarrow-circle-animation\u00bb heading_tag=\u00bbspan\u00bb link_type=\u00bbregular\u00bb button_color=\u00bbdefault\u00bb button_border_thickness=\u00bb0px\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbDispon\u00edvel na Banzai (Bolh\u00e3o)\u00bb url=\u00bbhttps:\/\/maps.app.goo.gl\/48AARCZNFAbsQxJA7&#8243;][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_video_lightbox link_style=\u00bbplay_button_2&#8243; nectar_play_button_color=\u00bbExtra-Color-3&#8243; image_url=\u00bb4907&#8243; hover_effect=\u00bbdefaut\u00bb box_shadow=\u00bbx_large_depth\u00bb border_radius=\u00bbnone\u00bb play_button_size=\u00bbdefault\u00bb video_url=\u00bbhttps:\/\/youtu.be\/eGeoIZwHMV4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb4912&#8243; bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbcenter center\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb3%\u00bb bottom_padding=\u00bb3%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb id=\u00bbsteps\u00bb row_name=\u00bbSign Up Steps\u00bb color_overlay=\u00bb#AE56E5&#8243; overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_to_right\u00bb enable_shape_divider=\u00bbtrue\u00bb shape_divider_position=\u00bbboth\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bbcurve\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb offset=\u00bbvc_col-xs-12&#8243;][nectar_icon_list color=\u00bbdefault\u00bb direction=\u00bbhorizontal\u00bb columns=\u00bbdefault\u00bb icon_size=\u00bbmedium\u00bb icon_style=\u00bbno-border\u00bb][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516895-6&#8243; header=\u00bb1-16 jugadores\u00bb text=\u00bbContamos con paquetes especiales para grupos de m\u00e1s de 16 jugadores\u00bb tab_id=\u00bb1776181516895-5&#8243; icon_fontawesome=\u00bbfa fa-users\u00bb][\/nectar_icon_list_item][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516911-1&#8243; header=\u00bb7+ a\u00f1os de edad\u00bb text=\u00bb\u00a1S\u00faper divertido de 7 a 70!<br \/>\nLos ni\u00f1os de 4 o 5 a\u00f1os pagan la mitad del precio cuando van acompa\u00f1ados de su familia.\u00bb tab_id=\u00bb1776181516912-9&#8243; icon_fontawesome=\u00bbfa fa-tachometer\u00bb][\/nectar_icon_list_item][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516924-9&#8243; header=\u00bbPluriling\u00fce\u00bb text=\u00bbSin barreras ling\u00fc\u00edsticas\u00bb tab_id=\u00bb1776181516925-10&#8243; icon_fontawesome=\u00bbfa fa-globe\u00bb][\/nectar_icon_list_item][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516936-0&#8243; header=\u00bbDiferentes duraciones de juego\u00bb text=\u00bb45 minutos es el est\u00e1ndar, pero tenemos otras duraciones de juego. Habla con nosotros. \u00bb tab_id=\u00bb1776181516937-6&#8243; icon_fontawesome=\u00bbfa fa-clock-o\u00bb][\/nectar_icon_list_item][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516948-6&#8243; header=\u00bbDiferentes modos de juego\u00bb text=\u00bbDiferentes experiencias cada vez que nos visitas\u00bb tab_id=\u00bb1776181516948-3&#8243; icon_fontawesome=\u00bbfa fa-star\u00bb][\/nectar_icon_list_item][nectar_icon_list_item icon_type=\u00bbicon\u00bb text_full_html=\u00bbsimple\u00bb title=\u00bbList Item\u00bb id=\u00bb1776181516954-1&#8243; header=\u00bbGran zona de juegos\u00bb text=\u00bb\u00a1El Pixel Arena m\u00e1s grande de Portugal, con 100 m\u00b2 de espacio total para que los grupos jueguen y se diviertan juntos!\u00bb tab_id=\u00bb1776181516955-6&#8243; icon_fontawesome=\u00bbfa fa-arrows-alt\u00bb][\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbcustom\u00bb column_margin_custom=\u00bb7%\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#f8f8f8&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bb30px\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb sticky_content=\u00bbtrue\u00bb sticky_content_functionality=\u00bbcss\u00bb sticky_content_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb font_size_max=\u00bb90px\u00bb text_direction=\u00bbdefault\u00bb font_size_desktop=\u00bb5vw\u00bb font_line_height=\u00bb1&#8243; font_size_tablet=\u00bb7vw\u00bb]\n<h3>Precios<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb text_direction=\u00bbdefault\u00bb]Disponemos de diferentes precios en funci\u00f3n del tiempo y n\u00famero de participantes.<\/p>\n<p>&nbsp;<\/p>\n<p>En l\u00ednea solo se pueden reservar los paquetes est\u00e1ndar (45min) pero tenemos otros paquetes con diferentes duraciones para diferentes tipos de grupos (empresas, fiestas de cumplea\u00f1os, despedidas de soltero, etc).<\/p>\n<p>Los participantes deben usar calcetines antideslizantes. Tambi\u00e9n lo tenemos a la venta en Banzai por solo 2\u20ac\/par. <\/p>\n<p><a href=\"mailto:team@banzai.pt\">\u00bfGrupos con m\u00e1s de 16 participantes? Habla con nosotros para +info<\/a>[\/nectar_responsive_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbnone\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbfontawesome\u00bb icon_style=\u00bbdefault\u00bb icon_color_type=\u00bbcolor_scheme\u00bb icon_color=\u00bbAccent-Color\u00bb icon_padding=\u00bb20px\u00bb pointer_events=\u00bball\u00bb icon_fontawesome=\u00bbfa fa-clock-o\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Precios por Nr de participantes (P) para 45 minutos de juego<\/h3>\n[\/nectar_responsive_text][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb2 P\u00bb col_2_content=\u00bb25 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb3 P\u00bb col_2_content=\u00bb20 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb4 P\u00bb col_2_content=\u00bb18 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb5 P\u00bb col_2_content=\u00bb17 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb6 P\u00bb col_2_content=\u00bb17 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb7 P\u00bb col_2_content=\u00bb17 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb8 P\u00bb col_2_content=\u00bb17 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb9P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb10P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb11P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb12P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb13P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb14P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb15P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][nectar_horizontal_list_item columns=\u00bb2&#8243; column_layout_using_2_columns=\u00bbeven\u00bb responsive_display=\u00bbmultiple_columns\u00bb col_1_text_align=\u00bbleft\u00bb col_2_text_align=\u00bbleft\u00bb col_1_text_element=\u00bbh3&#8243; col_2_text_element=\u00bbp\u00bb font_family=\u00bbp\u00bb hover_effect=\u00bbnone\u00bb border_animation=\u00bbtrue\u00bb border_color=\u00bb#424242&#8243; icon_family=\u00bbnone\u00bb icon_size=\u00bblarge\u00bb col_1_content=\u00bb16P (modo giratorio)\u00bb col_2_content=\u00bb15 \u20ac\/participante\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#eeee22&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb color_overlay=\u00bbrgba(238,238,34,0.84)\u00bb overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb enable_shape_divider=\u00bbtrue\u00bb shape_divider_position=\u00bbboth\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bbwaves\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft-right\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_custom_heading text=\u00bb\u00a1Vive el momento, prueba algo nuevo!\u00bb font_container=\u00bbtag:h2|font_size:52|text_align:center|line_height:52px\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb10&#8243;][vc_custom_heading text=\u00bbReserva a trav\u00e9s de la web o habla con nosotros v\u00eda whatsapp, tel\u00e9fono, email\u00bb font_container=\u00bbtag:p|text_align:center\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1737063391619{margin-top: 10px !important;margin-bottom: 10px !important;}\u00bb][nectar_btn size=\u00bbjumbo\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbExtra-Color-1&#8243; icon_family=\u00bbdefault_arrow\u00bb url=\u00bbhttps:\/\/banzai.pt\/es\/reservas-2\/\u00bb text=\u00bb\u00a1Reserva ahora!\u00bb css_animation=\u00bbzoomIn\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb color_overlay=\u00bbrgba(255,255,255,0.84)\u00bb overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#000000&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][nectar_responsive_text inherited_font_style=\u00bbdefault\u00bb text_direction=\u00bbdefault\u00bb]<div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?105914740381478ee276e5c8444\"><\/div>[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb4%\u00bb bottom_padding=\u00bb4%\u00bb top_padding_tablet=\u00bb16%\u00bb bottom_padding_tablet=\u00bb16%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_color=\u00bb#000000&#8243; shape_divider_position=\u00bbtop\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bbstraight_section\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bb0px\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][carousel script=\u00bbflickity\u00bb flickity_formatting=\u00bbdefault\u00bb desktop_cols_flickity=\u00bb4&#8243; desktop_small_cols_flickity=\u00bb3&#8243; tablet_cols_flickity=\u00bb2&#8243; phone_cols_flickity=\u00bb1&#8243; flickity_controls=\u00bbtouch_total\u00bb flickity_touch_total_style=\u00bbdefault\u00bb flickity_touch_total_hide_indicator=\u00bbtrue\u00bb flickity_touch_total_icon_color=\u00bbdark\u00bb color=\u00bbextra-color-2&#8243; flickity_overflow=\u00bbvisible\u00bb flickity_wrap_around=\u00bbno-wrap\u00bb flickity_spacing=\u00bb15px\u00bb flickity_column_vertical_alignment=\u00bbdefault\u00bb column_padding=\u00bb0&#8243; flickity_element_spacing=\u00bb0&#8243; flickity_image_scale_on_drag=\u00bbtrue\u00bb border_radius=\u00bbnone\u00bb][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517697-2&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517697-5&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4857&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517738-9&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517738-8&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4852&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517764-4&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517764-6&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4853&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517794-0&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517794-7&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4854&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517807-10&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517807-3&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4855&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][item simple_slider_bg_image_position=\u00bbdefault\u00bb simple_slider_overlay_strength=\u00bb0.3&#8243; simple_slider_bg_image_loading=\u00bbdefault\u00bb flickity_bg_image_loading=\u00bbdefault\u00bb flex_gap_desktop=\u00bb10px\u00bb flickity_item_link_type=\u00bbregular\u00bb id=\u00bb1776181517820-1&#8243; title=\u00bbItem\u00bb tab_id=\u00bb1776181517820-9&#8243;][fancy_box box_style=\u00bbimage_above_text_underline\u00bb image_url=\u00bb4856&#8243; image_aspect_ratio=\u00bb4-5&#8243; content_color=\u00bb#000000&#8243; border_radius=\u00bb10px\u00bb image_loading=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-right\u00bb image_size=\u00bblarge\u00bb link_url=\u00bbhttps:\/\/banzai.pt\/es\/desafio\/\u00bb link_screen_reader=\u00bbDaily anti-aging cream\u00bb][\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_gmap map_type=\u00bbgoogle\u00bb zoom=\u00bb16&#8243; enable_zoom=\u00bb1&#8243; marker_style=\u00bbnectar\u00bb nectar_marker_color=\u00bbextra-color-3&#8243; size=\u00bb750&#8243; map_center_lat=\u00bb41.1482921&#8243; map_center_lng=\u00bb-8.6079514&#8243; map_markers=\u00bb41.1482921|-8.6079514|Banzai Bolh\u00e3o\u00bb][\/vc_column][vc_column column_padding=\u00bbpadding-7-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color=\u00bb#F662A1&#8243; background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#FFFFFF\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb content_layout=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h3>Contactos<\/h3>\n<h5><\/h5>\n<h5>Direcci\u00f3n Banzai Bolh\u00e3o<\/h5>\n<p>Rua Dr. Ant\u00f3nio Em\u00edlio Magalh\u00e1es 24<\/p>\n<p>4000-090 Oporto, Portugal<\/p>\n<a class=\"nectar-button n-sc-button medium see-through-2\" target=\"_blank\" href=\"http:\/\/maps.google.com\/?q=41.1482921,-8.6079514\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Direcciones<\/span><\/a>\n<p>&nbsp;<\/p>\n<h5>Tel\u00e9fono y correo electr\u00f3nico<\/h5>\n<p>+351 22 328 22 22 (coste de llamar a la red fija nacional)<\/p>\n<p>info@banzai.pt[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#AE56E5&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb50&#8243; text_color=\u00bbcustom\u00bb custom_text_color=\u00bb#ffffff\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb font_color=\u00bb#ffffff\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#AE56E5&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][toggles style=\u00bbminimal\u00bb accordion=\u00bbtrue\u00bb accordion_starting_functionality=\u00bbclosed\u00bb][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfQu\u00e9 es Banzai Pixel?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]En Banzai Pixel, t\u00fa y tu equipo necesitar\u00e1n pensamiento r\u00e1pido, coordinaci\u00f3n impecable y movimientos \u00e1giles para superar docenas de niveles en un desaf\u00edo inmersivo donde el objetivo es anotar tantos puntos como sea posible.[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfDebo llevar ropa adecuada?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]En Banzai Pixel, juega con tu ropa c\u00f3moda de todos los d\u00edas, pero es obligatorio usar solo calcetines antideslizantes. Si no tienes calcetines antideslizantes, no hay problema, ya que tenemos nuestros preciosos calcetines antideslizantes Pink Pop a la venta en Banzai por solo 2\u20ac\/par.<br \/>\n\u00a1De esta manera, te asegurar\u00e1s la m\u00e1xima agilidad y comodidad para superar cada desaf\u00edo![\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfEs realmente para todas las edades?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1Por supuesto! Los equipos necesitan agilidad, pero tambi\u00e9n mucha coordinaci\u00f3n y estrategia. <\/p>\n<p>Los m\u00e1s peque\u00f1os, desde los 4 a\u00f1os, ya pueden entender y participar en la actividad, igual que los mayores, siempre que vayan acompa\u00f1ados de un adulto que pueda gestionar las emociones de los peque\u00f1os. \u00a1Es perfectamente adecuado para familias que quieren pasar una ma\u00f1ana o tarde llena de energ\u00eda!  \ud83d\ude42<\/p>\n<p>Los m\u00e1s experimentados pueden no tener la misma velocidad que los m\u00e1s j\u00f3venes, pero lo compensan con una visi\u00f3n estrat\u00e9gica y la capacidad de coordinar al equipo.[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bbC\u00f3mo funciona si se trata de un grupo completo de 12 a\u00f1os &lt;\u00ab][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Si se trata de un grupo con al menos 5 ni\u00f1os menores de 12 a\u00f1os, los adultos acompa\u00f1antes no pagan (hasta 2).[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfEs una actividad apta para familias?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1Es una de las actividades m\u00e1s memorables y divertidas para toda la familia! Con versiones de juego adaptadas a partir de los 4 a\u00f1os, garantizamos incre\u00edbles momentos de diversi\u00f3n para ni\u00f1os, padres e incluso abuelos.[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfTengo que reservar con antelaci\u00f3n?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]S\u00ed, recomendamos reservar con antelaci\u00f3n para asegurar la habitaci\u00f3n en el d\u00eda y hora que prefieras. Reservar es especialmente importante los fines de semana, cuando la demanda es mayor.  \u00a1Puedes reservar f\u00e1cilmente en nuestra web o contactarnos por correo electr\u00f3nico, WhatsApp o tel\u00e9fono![\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][toggles style=\u00bbminimal\u00bb accordion=\u00bbtrue\u00bb accordion_starting_functionality=\u00bbclosed\u00bb][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bbSi somos un grupo con m\u00e1s de 8, \u00bfc\u00f3mo funciona el modo rotatorio?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<p data-start=\"0\" data-end=\"151\">Recomendamos hasta 8 jugadores simult\u00e1neamente en la arena, ya que se ha dicho que puede ser m\u00e1s dif\u00edcil coordinar el equipo y sacar lo mejor del juego.<\/p>\n<p data-start=\"153\" data-end=\"514\">Aun as\u00ed, con 9 o m\u00e1s participantes, la experiencia sigue siendo extremadamente divertida y en\u00e9rgica. El grupo se divide en 2 o m\u00e1s equipos y juega en modo rotaci\u00f3n, alternando cada intento de nivel (u otros criterios que prefieran). Este formato no solo mantiene a todos ocupados, sino que tambi\u00e9n permite hacer breves pausas para recuperar el aliento entre asaltos.  <\/p>\n<p data-start=\"516\" data-end=\"645\" data-is-last-node=\"\" data-is-only-node=\"\">Te garantizamos: nadie se queda fuera y la adrenalina siempre se mantiene en su m\u00e1xima velocidad \u2014 \u00a1saldr\u00e1s de all\u00ed completamente \u00abconectado a la corriente\u00bb! \u26a1<\/p>\n[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bbSi somos un grupo mayor de 16, \u00bfpodemos jugar?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1S\u00ed! Pero en esos casos tendr\u00e1s que ponerte en contacto con nosotros previamente para ajustar los horarios y niveles de juego.[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfPuedo organizar una fiesta de cumplea\u00f1os y usar toda el \u00e1rea de juegos?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1Claro! Puedes reservar el espacio para tus invitados directamente en l\u00ednea. Y si tienes alguna duda, \u00a1ll\u00e1manos o escr\u00edbenos! Tenemos paquetes especiales para fiestas de cumplea\u00f1os, ya sea para ni\u00f1os o adultos, \u00a1asegurando una experiencia inolvidable! M\u00e1s informaci\u00f3n <a href=\"https:\/\/banzai.pt\/festas-de-aniversario\/\">aqu\u00ed<\/a>[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfPuedo organizar un evento de team building en Banzai Pixel?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\u00a1Claro! Organizamos eventos de team building personalizados y tenemos paquetes especiales que combinan incre\u00edbles actividades de Banzai, como el desafiante <em>Banzai Challenge<\/em>. Es la oportunidad perfecta para fortalecer la uni\u00f3n del equipo mientras se divierten y superan desaf\u00edos juntos. \u00a1Habla con nosotros y crea un evento inolvidable para tu grupo! M\u00e1s informaci\u00f3n <a href=\"https:\/\/banzai.pt\/es\/construccion-de-equipos\/\">aqu\u00ed<\/a>[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfQu\u00e9 tipos de pagos aceptamos?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Aceptamos efectivo, tarjetas de d\u00e9bito y cr\u00e9dito y MBWAY.<\/p>\n<p>Ten en cuenta que no se aceptan tarjetas temporales MBNET en nuestra web para realizar pagos de reservas anticipadas de 10 \u20ac.[\/vc_column_text][\/toggle][toggle color=\u00bbExtra-Color-3&#8243; heading_tag=\u00bbdefault\u00bb heading_tag_functionality=\u00bbdefault\u00bb title=\u00bb\u00bfD\u00f3nde puedo aparcar?\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]Estamos ubicados en el centro del centro de Oporto, a 1 minuto a pie de la estaci\u00f3n de metro de Bolh\u00e3o.<\/p>\n<p>Si vienes en coche, puedes aparcar en varios parques cubiertos como el Parque da Pra\u00e7a D. Jo\u00e3o I, el Parque do Bonjardim, el Shopping Via Catarina, entre otros aparcamientos disponibles en la zona.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb video_bg=\u00bbuse_video\u00bb video_webm=\u00bbhttps:\/\/banzai.pt\/wp-content\/uploads\/2025\/02\/banzai-pixel-teaser1-480p-nosound.webm\u00bb background_video_loading=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb advanced_gradient=\u00bblinear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,252) 0%, rgba(0,0,0,0) 43%)\u00bb enable_shape_divider=\u00bbtrue\u00bb shape_divider_position=\u00bbboth\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":73,"footnotes":""},"class_list":["post-5108","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00edxel - Banzai<\/title>\n<meta name=\"description\" content=\"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banzai.pt\/es\/pixel-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00edxel - Banzai\" \/>\n<meta property=\"og:description\" content=\"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banzai.pt\/es\/pixel-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Banzai\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T16:19:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"35 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/pixel-2\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/es\\\/pixel-2\\\/\",\"name\":\"P\u00edxel - Banzai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#website\"},\"datePublished\":\"2025-02-07T21:06:26+00:00\",\"dateModified\":\"2026-04-14T16:19:16+00:00\",\"description\":\"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/pixel-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banzai.pt\\\/es\\\/pixel-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/pixel-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/banzai.pt\\\/es\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00edxel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/banzai.pt\\\/es\\\/\",\"name\":\"Banzai\",\"description\":\"Banzai\",\"publisher\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banzai.pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#organization\",\"name\":\"Banzai\",\"url\":\"https:\\\/\\\/banzai.pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"contentUrl\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"width\":2560,\"height\":1870,\"caption\":\"Banzai\"},\"image\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00edxel - Banzai","description":"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banzai.pt\/es\/pixel-2\/","og_locale":"es_ES","og_type":"article","og_title":"P\u00edxel - Banzai","og_description":"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!","og_url":"https:\/\/banzai.pt\/es\/pixel-2\/","og_site_name":"Banzai","article_modified_time":"2026-04-14T16:19:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"35 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/banzai.pt\/es\/pixel-2\/","url":"https:\/\/banzai.pt\/es\/pixel-2\/","name":"P\u00edxel - Banzai","isPartOf":{"@id":"https:\/\/banzai.pt\/es\/#website"},"datePublished":"2025-02-07T21:06:26+00:00","dateModified":"2026-04-14T16:19:16+00:00","description":"\u00a1Game Floor es lava en Oporto! \u00a1La arena de p\u00edxeles m\u00e1s grande de Portugal te est\u00e1 esperando! \u00a1Ven a jugar al Floor is Lava en el Banzai!","breadcrumb":{"@id":"https:\/\/banzai.pt\/es\/pixel-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banzai.pt\/es\/pixel-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/banzai.pt\/es\/pixel-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/banzai.pt\/es\/casa\/"},{"@type":"ListItem","position":2,"name":"P\u00edxel"}]},{"@type":"WebSite","@id":"https:\/\/banzai.pt\/es\/#website","url":"https:\/\/banzai.pt\/es\/","name":"Banzai","description":"Banzai","publisher":{"@id":"https:\/\/banzai.pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banzai.pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/banzai.pt\/es\/#organization","name":"Banzai","url":"https:\/\/banzai.pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/banzai.pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","contentUrl":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","width":2560,"height":1870,"caption":"Banzai"},"image":{"@id":"https:\/\/banzai.pt\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/pages\/5108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/comments?post=5108"}],"version-history":[{"count":11,"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/pages\/5108\/revisions"}],"predecessor-version":[{"id":6332,"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/pages\/5108\/revisions\/6332"}],"wp:attachment":[{"href":"https:\/\/banzai.pt\/es\/wp-json\/wp\/v2\/media?parent=5108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}