{"id":6660,"date":"2026-09-01T10:38:52","date_gmt":"2026-09-01T10:38:52","guid":{"rendered":"https:\/\/banzai.pt\/banzai-bolhao\/"},"modified":"2026-09-01T10:38:53","modified_gmt":"2026-09-01T10:38:53","slug":"banzai-bolhao","status":"publish","type":"page","link":"https:\/\/banzai.pt\/en\/banzai-bolhao\/","title":{"rendered":"Banzai Bolh\u00e3o"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F662A1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;8%&#8221; top_padding_tablet=&#8221;16%&#8221; bottom_padding_tablet=&#8221;16%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;both&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;30&#8243; bottom_padding_tablet=&#8221;20&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;small_desktop&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;ltr&#8221;]\n<h2>Experiences available at Banzai (Bolh\u00e3o)<\/h2>\n<p>Try our Action Games and take advantage of a super central location close to restaurants, bars and parking[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_cta btn_style=&#8221;underline&#8221; underline_visibility=&#8221;default&#8221; heading_tag=&#8221;span&#8221; border_radius=&#8221;20&#8243; link_type=&#8221;new_tab&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;right&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;fontawesome&#8221; icon_alignment=&#8221;left&#8221; link_text=&#8221;Rua dr. Ant\u00f3nio Em\u00edlio Magalh\u00e3es 24 (pr\u00f3ximo do mercado do Bolh\u00e3o)&#8221; url=&#8221;https:\/\/maps.app.goo.gl\/RLpkYijAmTGDipge8&#8243; icon_fontawesome=&#8221;fa fa-map-marker&#8221;][\/vc_column_inner][\/vc_row_inner][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;4&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_controls=&#8221;touch_total&#8221; flickity_touch_total_style=&#8221;default&#8221; flickity_touch_total_hide_indicator=&#8221;true&#8221; flickity_touch_total_icon_color=&#8221;dark&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_spacing=&#8221;default&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; border_radius=&#8221;none&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1788258453990-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1788258453990-10&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;5655&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221; link_url=&#8221;https:\/\/banzai.pt\/en\/reservations\/&#8221; link_screen_reader=&#8221;Daily anti-aging cream&#8221;]\n<h4>Banzai Challenge<\/h4>\n<p>Unique sensory adventure in the world! Test your 5 senses to the fullest and have fun like never before[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1788258454009-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1788258454009-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;6409&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221; delay=&#8221;100&#8243; link_url=&#8221;https:\/\/banzai.pt\/en\/pixel\/&#8221;]\n<h4>Banzai Pixel Max<\/h4>\n<p>Jump and laugh out loud in our latest challenge![\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1788258454045-3&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1788258454046-9&#8243;][fancy_box box_style=&#8221;image_above_text_underline&#8221; image_url=&#8221;5661&#8243; image_aspect_ratio=&#8221;4-5&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; image_size=&#8221;large&#8221; delay=&#8221;200&#8243; link_url=&#8221;https:\/\/banzai.pt\/en\/bomb\/&#8221;]\n<h4>Banzai Bomb<\/h4>\n<p>Defuse a bomb before it explodes in your hands![\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_gmap map_type=&#8221;google&#8221; zoom=&#8221;13&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; nectar_marker_color=&#8221;extra-color-1&#8243; map_greyscale=&#8221;1&#8243; map_color=&#8221;#E53156&#8243; size=&#8221;750&#8243; map_center_lat=&#8221;41.148437591561915&#8243; map_center_lng=&#8221;-8.607522248448976&#8243; map_markers=&#8221;41.148437591561915| -8.607522248448976| Banzai (Bolh\u00e3o) 41.14789135584444| -8.614495648448976| Porto Exit Games (Baixa) 41.16184857085167| -8.581846604268081| Porto Exit Games (Drag\u00e3o) 41.158008237143584| -8.609529342890362| Banzai (Cam\u00f5es)&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;bounceIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]All our locations are close to metro stations and car<\/p>\n<p>parks Tel: +351 22 328 22 22<\/p>\n<p>Email: info@banzai.pt[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F662A1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;8%&#8221; top_padding_tablet=&#8221;16%&#8221; bottom_padding_tablet=&#8221;16%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;both&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":0,"footnotes":""},"class_list":["post-6660","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto<\/title>\n<meta name=\"description\" content=\"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banzai.pt\/en\/banzai-bolhao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto\" \/>\n<meta property=\"og:description\" content=\"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banzai.pt\/en\/banzai-bolhao\/\" \/>\n<meta property=\"og:site_name\" content=\"Banzai\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banzai.pt\/wp-content\/uploads\/2020\/07\/banzai-hero2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/banzai-bolhao\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/banzai-bolhao\\\/\",\"name\":\"The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#website\"},\"datePublished\":\"2026-09-01T10:38:52+00:00\",\"dateModified\":\"2026-09-01T10:38:53+00:00\",\"description\":\"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/banzai-bolhao\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banzai.pt\\\/en\\\/banzai-bolhao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/banzai-bolhao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/banzai.pt\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banzai Bolh\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/\",\"name\":\"Banzai\",\"description\":\"Banzai - Play. Connect. Remember.\",\"publisher\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banzai.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#organization\",\"name\":\"Banzai\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"contentUrl\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"width\":2560,\"height\":1870,\"caption\":\"Banzai\"},\"image\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto","description":"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banzai.pt\/en\/banzai-bolhao\/","og_locale":"en_US","og_type":"article","og_title":"The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto","og_description":"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.","og_url":"https:\/\/banzai.pt\/en\/banzai-bolhao\/","og_site_name":"Banzai","article_modified_time":"2026-09-01T10:38:53+00:00","og_image":[{"url":"https:\/\/banzai.pt\/wp-content\/uploads\/2020\/07\/banzai-hero2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/banzai.pt\/en\/banzai-bolhao\/","url":"https:\/\/banzai.pt\/en\/banzai-bolhao\/","name":"The best Action Games, Escape Rooms, Team Building Activities and Birthday Parties in Porto","isPartOf":{"@id":"https:\/\/banzai.pt\/en\/#website"},"datePublished":"2026-09-01T10:38:52+00:00","dateModified":"2026-09-01T10:38:53+00:00","description":"Original Team Activities Perfect for Team Building Events, Birthday Parties, Bachelor Parties, etc.","breadcrumb":{"@id":"https:\/\/banzai.pt\/en\/banzai-bolhao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banzai.pt\/en\/banzai-bolhao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/banzai.pt\/en\/banzai-bolhao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/banzai.pt\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Banzai Bolh\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/banzai.pt\/en\/#website","url":"https:\/\/banzai.pt\/en\/","name":"Banzai","description":"Banzai - Play. Connect. Remember.","publisher":{"@id":"https:\/\/banzai.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banzai.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/banzai.pt\/en\/#organization","name":"Banzai","url":"https:\/\/banzai.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/banzai.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","contentUrl":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","width":2560,"height":1870,"caption":"Banzai"},"image":{"@id":"https:\/\/banzai.pt\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/6660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/comments?post=6660"}],"version-history":[{"count":2,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/6660\/revisions"}],"predecessor-version":[{"id":6662,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/6660\/revisions\/6662"}],"wp:attachment":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/media?parent=6660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}