{"id":508,"date":"2019-08-09T19:37:24","date_gmt":"2019-08-09T19:37:24","guid":{"rendered":"https:\/\/banzai.pt\/games\/"},"modified":"2020-06-10T17:17:31","modified_gmt":"2020-06-10T17:17:31","slug":"games","status":"publish","type":"page","link":"https:\/\/banzai.pt\/en\/games\/","title":{"rendered":"Games"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;Our games&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;accent-color&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;40&#8243; custom_line_width=&#8221;40&#8243;][vc_column_text max_width=&#8221;650&#8243;]All Originals! All fun! Always unforgettable experiences:)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221;][team_member image_url=&#8221;19&#8243; team_memeber_style=&#8221;meta_overlaid_alt&#8221; link_url_2=&#8221;https:\/\/banzai.pt\/challenge\/&#8221; name=&#8221;Banzai Challenge&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221;][team_member image_url=&#8221;18&#8243; team_memeber_style=&#8221;meta_overlaid_alt&#8221; link_url_2=&#8221;https:\/\/banzai.pt\/bomb\/&#8221; name=&#8221;Banzai Bomb&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;grow-in&#8221;][team_member image_url=&#8221;124&#8243; team_memeber_style=&#8221;meta_overlaid_alt&#8221; link_url_2=&#8221;https:\/\/portoexitgames.com&#8221; name=&#8221;Exit Games&#8221; job_position=&#8221;Located 6 min walk from Banzai&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":394,"footnotes":""},"class_list":["post-508","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Games - Banzai<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banzai.pt\/en\/games\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Games - Banzai\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banzai.pt\/en\/games\/\" \/>\n<meta property=\"og:site_name\" content=\"Banzai\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-10T17:17:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/games\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/games\\\/\",\"name\":\"Games - Banzai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#website\"},\"datePublished\":\"2019-08-09T19:37:24+00:00\",\"dateModified\":\"2020-06-10T17:17:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/games\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banzai.pt\\\/en\\\/games\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/games\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/banzai.pt\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Games\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/\",\"name\":\"Banzai\",\"description\":\"Banzai - Play. Connect. Remember.\",\"publisher\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banzai.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#organization\",\"name\":\"Banzai\",\"url\":\"https:\\\/\\\/banzai.pt\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"contentUrl\":\"https:\\\/\\\/banzai.pt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/hero.png\",\"width\":2560,\"height\":1870,\"caption\":\"Banzai\"},\"image\":{\"@id\":\"https:\\\/\\\/banzai.pt\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Games - Banzai","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banzai.pt\/en\/games\/","og_locale":"en_US","og_type":"article","og_title":"Games - Banzai","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221;...","og_url":"https:\/\/banzai.pt\/en\/games\/","og_site_name":"Banzai","article_modified_time":"2020-06-10T17:17:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/banzai.pt\/en\/games\/","url":"https:\/\/banzai.pt\/en\/games\/","name":"Games - Banzai","isPartOf":{"@id":"https:\/\/banzai.pt\/en\/#website"},"datePublished":"2019-08-09T19:37:24+00:00","dateModified":"2020-06-10T17:17:31+00:00","breadcrumb":{"@id":"https:\/\/banzai.pt\/en\/games\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banzai.pt\/en\/games\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/banzai.pt\/en\/games\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/banzai.pt\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Games"}]},{"@type":"WebSite","@id":"https:\/\/banzai.pt\/en\/#website","url":"https:\/\/banzai.pt\/en\/","name":"Banzai","description":"Banzai - Play. Connect. Remember.","publisher":{"@id":"https:\/\/banzai.pt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banzai.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/banzai.pt\/en\/#organization","name":"Banzai","url":"https:\/\/banzai.pt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/banzai.pt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","contentUrl":"https:\/\/banzai.pt\/wp-content\/uploads\/2019\/07\/hero.png","width":2560,"height":1870,"caption":"Banzai"},"image":{"@id":"https:\/\/banzai.pt\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":6,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/508\/revisions"}],"predecessor-version":[{"id":962,"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/pages\/508\/revisions\/962"}],"wp:attachment":[{"href":"https:\/\/banzai.pt\/en\/wp-json\/wp\/v2\/media?parent=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}